{"id":4504,"date":"2018-10-17T11:07:48","date_gmt":"2018-10-17T09:07:48","guid":{"rendered":"http:\/\/nebeskestolice.com\/ns2-61-apartman\/"},"modified":"2019-06-24T15:42:20","modified_gmt":"2019-06-24T13:42:20","slug":"ns2-61-apartment","status":"publish","type":"page","link":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/","title":{"rendered":"NS2 6+1 Apartment"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1539691377456{margin-left: 200px !important;}&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1539691576974{margin-left: 200px !important;}&#8221;][vc_gallery type=&#8221;flexslider_slide&#8221; interval=&#8221;3&#8243; images=&#8221;4511,4507,4508,4509,4510&#8243; img_size=&#8221;full&#8221;][vc_empty_space]            <div class=\"innovation-heading style2 \" >\r\n                                    <h2>NS2 6+1 Apartment<\/h2>\r\n                                            <p>Two bedroom, double bed and one single bed in the first, double bed and one single bed in the and sofa-bed for two in the living room, two bathrooms (max 8 persons)<\/p>\r\n                                                <\/div>\r\n            [vc_column_text el_class=&#8221;align-icon&#8221; css=&#8221;.vc_custom_1542984024496{margin-top: 10px !important;margin-bottom: 30px !important;}&#8221;]<\/p>\n<div class=\"inline-icon\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4046 alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png\" alt=\"\" width=\"50\" height=\"44\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4050 size-full alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/minibar..png\" alt=\"\" width=\"50\" height=\"44\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4053 alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/room-servis.png\" alt=\"\" width=\"50\" height=\"44\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4056 size-full alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/tv.png\" alt=\"\" width=\"50\" height=\"44\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4054 alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/telefon.png\" alt=\"\" width=\"50\" height=\"44\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4044 alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/fen-1.png\" alt=\"\" width=\"50\" height=\"44\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4057 alignnone\" src=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/wifi.png\" alt=\"\" width=\"50\" height=\"44\" \/><\/div>\n<p>[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4589-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/4504#wpcf7-f4589-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"4589\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4589-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Name (*)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Phone (*)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-333\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-333\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0415mail (*)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Number of adults<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-125\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"6\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"number-125\" \/><\/span> <\/label>\n<\/p>\n<p><label> Number of children<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-193\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"0\" max=\"6\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"number-193\" \/><\/span> <\/label>\n<\/p>\n<p><label> Check-in Date<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-70\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\u0414\u0430\u0442\u0443\u043c \u043f\u0440\u0438\u0458\u0430\u0432\u0435\" type=\"date\" name=\"date-70\" \/><\/span> <\/label>\n<\/p>\n<p><label> Check-out Date<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-701\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\u0414\u0430\u0442\u0443\u043c \u043e\u0434\u0458\u0430\u0432\u0435\" type=\"date\" name=\"date-701\" \/><\/span> <\/label>\n<\/p>\n<p><label> Accommodation<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tipsmestaja\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"tipsmestaja\"><option value=\"\">&#8212;Please choose an option&#8212;<\/option><option value=\"NS2 - 1\/2 Room\">NS2 - 1\/2 Room<\/option><option value=\"NS2 - 1\/2+1 Room\">NS2 - 1\/2+1 Room<\/option><option value=\"NS2 - 1\/3+1 Room\">NS2 - 1\/3+1 Room<\/option><option value=\"NS2 - 1\/3+2 Room\">NS2 - 1\/3+2 Room<\/option><option value=\"NS2 - 2+1 Apartment\">NS2 - 2+1 Apartment<\/option><option value=\"NS2 - 3+1 Apartment\">NS2 - 3+1 Apartment<\/option><option value=\"NS2 - 4+1 Apartment\">NS2 - 4+1 Apartment<\/option><option value=\"NS2 - 5+1 Apartment\">NS2 - 5+1 Apartment<\/option><option value=\"NS2 - 6+1 Apartment\">NS2 - 6+1 Apartment<\/option><\/select><\/span> <\/label>\n<\/p>\n<p><label> Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1539691377456{margin-left: 200px !important;}&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1539691576974{margin-left: 200px !important;}&#8221;][vc_gallery type=&#8221;flexslider_slide&#8221; interval=&#8221;3&#8243; images=&#8221;4511,4507,4508,4509,4510&#8243; img_size=&#8221;full&#8221;][vc_empty_space][vc_column_text el_class=&#8221;align-icon&#8221; css=&#8221;.vc_custom_1542984024496{margin-top: 10px !important;margin-bottom: 30px !important;}&#8221;] [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NS2 6+1 Apartment - \u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435<\/title>\n<meta name=\"description\" content=\"Book a comfortable apartment for 6-8 persons within the aparthotel Nebeska Stolica 2 on Kopaonik. Ideal accommodation for holidays and winter activities on the mountain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NS2 6+1 Apartment - \u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435\" \/>\n<meta property=\"og:description\" content=\"Book a comfortable apartment for 6-8 persons within the aparthotel Nebeska Stolica 2 on Kopaonik. Ideal accommodation for holidays and winter activities on the mountain.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/\" \/>\n<meta property=\"og:site_name\" content=\"\u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-24T13:42:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/\",\"url\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/\",\"name\":\"NS2 6+1 Apartment - \u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435\",\"isPartOf\":{\"@id\":\"https:\/\/nebeskestolice.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png\",\"datePublished\":\"2018-10-17T09:07:48+00:00\",\"dateModified\":\"2019-06-24T13:42:20+00:00\",\"description\":\"Book a comfortable apartment for 6-8 persons within the aparthotel Nebeska Stolica 2 on Kopaonik. Ideal accommodation for holidays and winter activities on the mountain.\",\"breadcrumb\":{\"@id\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#primaryimage\",\"url\":\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png\",\"contentUrl\":\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nebeskestolice.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NS2 6+1 Apartment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nebeskestolice.com\/#website\",\"url\":\"https:\/\/nebeskestolice.com\/\",\"name\":\"\u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435\",\"description\":\"\u041a\u043e\u043f\u0430\u043e\u043d\u0438\u043a\",\"publisher\":{\"@id\":\"https:\/\/nebeskestolice.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nebeskestolice.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nebeskestolice.com\/#organization\",\"name\":\"Nebeske stolice\",\"url\":\"https:\/\/nebeskestolice.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nebeskestolice.com\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/09\/logo-nebeske-stolice.png\",\"contentUrl\":\"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/09\/logo-nebeske-stolice.png\",\"width\":186,\"height\":148,\"caption\":\"Nebeske stolice\"},\"image\":{\"@id\":\"https:\/\/nebeskestolice.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NS2 6+1 Apartment - \u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435","description":"Book a comfortable apartment for 6-8 persons within the aparthotel Nebeska Stolica 2 on Kopaonik. Ideal accommodation for holidays and winter activities on the mountain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/","og_locale":"en_US","og_type":"article","og_title":"NS2 6+1 Apartment - \u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435","og_description":"Book a comfortable apartment for 6-8 persons within the aparthotel Nebeska Stolica 2 on Kopaonik. Ideal accommodation for holidays and winter activities on the mountain.","og_url":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/","og_site_name":"\u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435","article_modified_time":"2019-06-24T13:42:20+00:00","og_image":[{"url":"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/","url":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/","name":"NS2 6+1 Apartment - \u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435","isPartOf":{"@id":"https:\/\/nebeskestolice.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#primaryimage"},"image":{"@id":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#primaryimage"},"thumbnailUrl":"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png","datePublished":"2018-10-17T09:07:48+00:00","dateModified":"2019-06-24T13:42:20+00:00","description":"Book a comfortable apartment for 6-8 persons within the aparthotel Nebeska Stolica 2 on Kopaonik. Ideal accommodation for holidays and winter activities on the mountain.","breadcrumb":{"@id":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#primaryimage","url":"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png","contentUrl":"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/11\/pribor.png"},{"@type":"BreadcrumbList","@id":"http:\/\/nebeskestolice.com\/en\/ns2-61-apartment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nebeskestolice.com\/"},{"@type":"ListItem","position":2,"name":"NS2 6+1 Apartment"}]},{"@type":"WebSite","@id":"https:\/\/nebeskestolice.com\/#website","url":"https:\/\/nebeskestolice.com\/","name":"\u041d\u0435\u0431\u0435\u0441\u043a\u0435 \u0421\u0442\u043e\u043b\u0438\u0446\u0435","description":"\u041a\u043e\u043f\u0430\u043e\u043d\u0438\u043a","publisher":{"@id":"https:\/\/nebeskestolice.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nebeskestolice.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nebeskestolice.com\/#organization","name":"Nebeske stolice","url":"https:\/\/nebeskestolice.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nebeskestolice.com\/#\/schema\/logo\/image\/","url":"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/09\/logo-nebeske-stolice.png","contentUrl":"http:\/\/nebeskestolice.com\/wp-content\/uploads\/2018\/09\/logo-nebeske-stolice.png","width":186,"height":148,"caption":"Nebeske stolice"},"image":{"@id":"https:\/\/nebeskestolice.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/pages\/4504"}],"collection":[{"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/comments?post=4504"}],"version-history":[{"count":0,"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/pages\/4504\/revisions"}],"wp:attachment":[{"href":"http:\/\/nebeskestolice.com\/en\/wp-json\/wp\/v2\/media?parent=4504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}